{"id":2678,"count":99,"description":"","link":"https:\/\/www.movemobility.ca\/fr\/resources\/category\/wheelchair-accessible-minivans\/","name":"Minivans accessibles aux fauteuils roulants","slug":"wheelchair-accessible-minivans","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wheelchair Accessible Minivans Archives - MoveMobility - Wheelchair Van Conversions<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wheelchair Accessible Minivans Archives - MoveMobility - Wheelchair Van Conversions\" \/>\n<meta property=\"og:url\" content=\"https:\/\/movemobility.ca\/resources\/category\/wheelchair-accessible-minivans\/\" \/>\n<meta property=\"og:site_name\" content=\"MoveMobility\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@mobility_move\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/movemobility.ca\/resources\/category\/wheelchair-accessible-minivans\/\",\"url\":\"https:\/\/movemobility.ca\/resources\/category\/wheelchair-accessible-minivans\/\",\"name\":\"Wheelchair Accessible Minivans Archives - MoveMobility - Wheelchair Van Conversions\",\"isPartOf\":{\"@id\":\"https:\/\/movemobility.ca\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/movemobility.ca\/resources\/category\/wheelchair-accessible-minivans\/#breadcrumb\"},\"inLanguage\":\"fr-CA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/movemobility.ca\/resources\/category\/wheelchair-accessible-minivans\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Wheelchair Accessible Vans &amp; Medical Vehicles\",\"item\":\"https:\/\/www.movemobility.ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wheelchair Accessible Minivans\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/movemobility.ca\/#website\",\"url\":\"https:\/\/movemobility.ca\/\",\"name\":\"MoveMobility\",\"description\":\"Wheelchair Accessible Vans &amp; Medical Vehicles\",\"publisher\":{\"@id\":\"https:\/\/movemobility.ca\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/movemobility.ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/movemobility.ca\/#organization\",\"name\":\"MoveMobility\",\"url\":\"https:\/\/movemobility.ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/movemobility.ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.movemobility.ca\/wp-content\/uploads\/2021\/06\/MM_logo_Stacked-LG.png\",\"contentUrl\":\"https:\/\/www.movemobility.ca\/wp-content\/uploads\/2021\/06\/MM_logo_Stacked-LG.png\",\"width\":444,\"height\":114,\"caption\":\"MoveMobility\"},\"image\":{\"@id\":\"https:\/\/movemobility.ca\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/mobilitymove\/\",\"https:\/\/x.com\/mobility_move\",\"https:\/\/www.linkedin.com\/company\/3961770\/\",\"https:\/\/www.youtube.com\/channel\/UCiW-UIxjD6wjjX-7KS4z22g\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wheelchair Accessible Minivans Archives - MoveMobility - Wheelchair Van Conversions","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_CA","og_type":"article","og_title":"Wheelchair Accessible Minivans Archives - MoveMobility - Wheelchair Van Conversions","og_url":"https:\/\/movemobility.ca\/resources\/category\/wheelchair-accessible-minivans\/","og_site_name":"MoveMobility","twitter_card":"summary_large_image","twitter_site":"@mobility_move","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/movemobility.ca\/resources\/category\/wheelchair-accessible-minivans\/","url":"https:\/\/movemobility.ca\/resources\/category\/wheelchair-accessible-minivans\/","name":"Wheelchair Accessible Minivans Archives - MoveMobility - Wheelchair Van Conversions","isPartOf":{"@id":"https:\/\/movemobility.ca\/#website"},"breadcrumb":{"@id":"https:\/\/movemobility.ca\/resources\/category\/wheelchair-accessible-minivans\/#breadcrumb"},"inLanguage":"fr-CA"},{"@type":"BreadcrumbList","@id":"https:\/\/movemobility.ca\/resources\/category\/wheelchair-accessible-minivans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Wheelchair Accessible Vans &amp; Medical Vehicles","item":"https:\/\/www.movemobility.ca\/"},{"@type":"ListItem","position":2,"name":"Wheelchair Accessible Minivans"}]},{"@type":"WebSite","@id":"https:\/\/movemobility.ca\/#website","url":"https:\/\/movemobility.ca\/","name":"MoveMobility","description":"Fourgons et v\u00e9hicules m\u00e9dicaux accessibles aux fauteuils roulants","publisher":{"@id":"https:\/\/movemobility.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/movemobility.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/movemobility.ca\/#organization","name":"MoveMobility","url":"https:\/\/movemobility.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/movemobility.ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.movemobility.ca\/wp-content\/uploads\/2021\/06\/MM_logo_Stacked-LG.png","contentUrl":"https:\/\/www.movemobility.ca\/wp-content\/uploads\/2021\/06\/MM_logo_Stacked-LG.png","width":444,"height":114,"caption":"MoveMobility"},"image":{"@id":"https:\/\/movemobility.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mobilitymove\/","https:\/\/x.com\/mobility_move","https:\/\/www.linkedin.com\/company\/3961770\/","https:\/\/www.youtube.com\/channel\/UCiW-UIxjD6wjjX-7KS4z22g\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.movemobility.ca\/fr\/wp-json\/wp\/v2\/categories\/2678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.movemobility.ca\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.movemobility.ca\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.movemobility.ca\/fr\/wp-json\/wp\/v2\/posts?categories=2678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}